{"id":10,"date":"2020-04-11T17:17:27","date_gmt":"2020-04-11T08:17:27","guid":{"rendered":"https:\/\/lion-cafe.work\/recruitment\/?page_id=10"},"modified":"2026-02-27T17:35:18","modified_gmt":"2026-02-27T08:35:18","slug":"contact-2","status":"publish","type":"page","link":"https:\/\/lion-cafe.work\/recruitment\/contact-2\/","title":{"rendered":"\u304a\u554f\u3044\u5408\u308f\u305b"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76\" src=\"https:\/\/lion-cafe.work\/recruitment\/wp\/wp-content\/uploads\/contact.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/lion-cafe.work\/recruitment\/wp\/wp-content\/uploads\/contact.jpg 640w, https:\/\/lion-cafe.work\/recruitment\/wp\/wp-content\/uploads\/contact-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfOJS1mHEAblEOS1PJJ9Q5oGhjWOYsUKyjOMSeTM7oRNMxtAA\/viewform?embedded=true\" width=\"100%\" height=\"1096\" frameborder=\"0\" marginheight=\"0\" marginwidth=\"0\">\u8aad\u307f\u8fbc\u3093\u3067\u3044\u307e\u3059\u2026<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u8aad\u307f\u8fbc\u3093\u3067\u3044\u307e\u3059\u2026<\/p>\n","protected":false},"author":1,"featured_media":76,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":9,"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":208,"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/pages\/10\/revisions\/208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/media\/76"}],"wp:attachment":[{"href":"https:\/\/lion-cafe.work\/recruitment\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}